{"id":23938,"date":"2015-03-24T15:48:22","date_gmt":"2015-03-24T21:48:22","guid":{"rendered":"http:\/\/mesoamericaregion.org\/es\/?post_type=wpdmpro&#038;p=23938"},"modified":"2021-11-01T21:27:22","modified_gmt":"2021-11-02T03:27:22","slug":"un-bout-de-chemin-dans-la-bonne-direction","status":"publish","type":"wpdmpro","link":"https:\/\/www.mesonaz.org\/fr\/package\/un-bout-de-chemin-dans-la-bonne-direction\/","title":{"rendered":"Un bout de chemin dans la bonne direction (Jeunesse)"},"content":{"rendered":"<p>Christianisme. Saintet\u00e9. Mission. Il y a des questions qui touchent de pr\u00e8s ces th\u00e8mes et que bon nombre d\u2019entre nous avons pos\u00e9es ou qui nous ont \u00e9t\u00e9 pos\u00e9es par d\u2019autres. Certains ont pris du temps pour y r\u00e9fl\u00e9chir et comme c\u2019est le cas habituellement, d\u2019autres questions personnelles s\u2019y sont ajout\u00e9es. Nous, nous les avons \u00e9crites noir sur blanc pour qu\u2019ensemble nous puissions nous embarquer dans un voyage.<\/p>\n<p>Ce que vous tenez dans votre main n\u2019est rien que le d\u00e9but. Ce ne sont que quelques questions et le d\u00e9but de r\u00e9ponses. Elles ne sont pas cens\u00e9es \u00eatre exhaustives ni \u00e9videntes. Elles ont juste pour but de vous amener \u00e0 r\u00e9fl\u00e9chir. Et ensemble, avec d\u2019autres qui sont en route pour ce voyage, avec l\u2019aide de Dieu, nous aimerions d\u00e9couvrir encore plus de r\u00e9ponses.<\/p>\n<p>Il n\u2019y a aucune mani\u00e8re prescrite d\u2019utiliser ce livre, mais il serait probablement plus efficace si vous exploriez les questions et les r\u00e9ponses avec les personnes qui vous entourent. M\u00eame \u00e9tant assis sur des bancs dans une \u00e9glise ou autour d\u2019une table dans votre caf\u00e9 pr\u00e9f\u00e9r\u00e9, libre \u00e0 vous. Tout ce que nous vous demandons, c\u2019est de chercher honn\u00eatement des r\u00e9ponses au-del\u00e0 de celles d\u00e9j\u00e0 donn\u00e9es, et de ne pas cessez de vous poser ces questions, mais \u00e9galement d\u2019autres.<\/p>\n<p>Vous pouvez t\u00e9l\u00e9charger ici la version \u00e9lectronique compl\u00e8te ou acheter une copie dans le bureau MAR des Minist\u00e8res R\u00e9gionales de la Formation de Disciples.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Christianisme. Saintet\u00e9. Mission. Il y a des questions qui touchent de pr\u00e8s ces th\u00e8mes et que bon nombre d\u2019entre nous avons pos\u00e9es ou qui nous ont \u00e9t\u00e9 pos\u00e9es par d\u2019autres. Certains ont pris du temps pour y r\u00e9fl\u00e9chir et comme c\u2019est le cas habituellement, d\u2019autres questions personnelles s\u2019y sont ajout\u00e9es. Nous, nous les avons \u00e9crites <a href=\"https:\/\/www.mesonaz.org\/fr\/package\/un-bout-de-chemin-dans-la-bonne-direction\/\"> <\/a><\/p>\n","protected":false},"author":22,"featured_media":23940,"comment_status":"open","ping_status":"closed","template":"","meta":{"__wpdm_changelog":[]},"wpdmcategory":[1073,4355,2050,3204],"wpdmtag":[],"class_list":["post-23938","wpdmpro","type-wpdmpro","status-publish","has-post-thumbnail","hentry","wpdmcategory-discipolat-fr","wpdmcategory-la-grace-salvatrice-du-bapteme-a-ladhesion-pour-jeunes","wpdmcategory-jeunes","wpdmcategory-telecharger"],"_links":{"self":[{"href":"https:\/\/www.mesonaz.org\/fr\/wp-json\/wp\/v2\/wpdmpro\/23938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesonaz.org\/fr\/wp-json\/wp\/v2\/wpdmpro"}],"about":[{"href":"https:\/\/www.mesonaz.org\/fr\/wp-json\/wp\/v2\/types\/wpdmpro"}],"author":[{"embeddable":true,"href":"https:\/\/www.mesonaz.org\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mesonaz.org\/fr\/wp-json\/wp\/v2\/comments?post=23938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mesonaz.org\/fr\/wp-json\/wp\/v2\/media\/23940"}],"wp:attachment":[{"href":"https:\/\/www.mesonaz.org\/fr\/wp-json\/wp\/v2\/media?parent=23938"}],"wp:term":[{"taxonomy":"wpdmcategory","embeddable":true,"href":"https:\/\/www.mesonaz.org\/fr\/wp-json\/wp\/v2\/wpdmcategory?post=23938"},{"taxonomy":"wpdmtag","embeddable":true,"href":"https:\/\/www.mesonaz.org\/fr\/wp-json\/wp\/v2\/wpdmtag?post=23938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}