{"id":57703,"date":"2019-08-21T12:07:48","date_gmt":"2019-08-21T18:07:48","guid":{"rendered":"https:\/\/www.mesonaz.org\/?p=57703"},"modified":"2019-11-01T15:31:04","modified_gmt":"2019-11-01T21:31:04","slug":"more-than-600-people-baptized-in-guatemala-district","status":"publish","type":"post","link":"https:\/\/www.mesonaz.org\/en\/more-than-600-people-baptized-in-guatemala-district\/","title":{"rendered":"More than 600 People Baptized in Guatemala District"},"content":{"rendered":"<p>On Sunday August 18th, approximately 8,500 people attended a mass baptism celebration held for the first time by the Church of the Nazarene Verapaz North District in Guatemala. The District&#8217;s 105 churches came together to celebrate the baptism of 697 persons.<\/p>\n<p>Starting out from their different locations in the early hours of the morning, the churches journeyed with their baptism candidates to the El Manantial recreational park in Santa Cruz Verapaz. There they were welcomed by the sounds of a marimba and had a time of devotion featuring the pastors&#8217; wives choir and the Church of the Nazarene Coban Central choir who sang beautiful songs of praise.<\/p>\n<p>District Superintendent, Rev. Francisco Cho Si preached the sermon which was entitled: &#8220;Six thousand temples of the Holy Spirit&#8221;. With the church buildings being closed that Sunday, he said that all were invited to open their hearts to receive the work of the Holy Spirit. according to\u00a0the apostle Paul in\u00a01 Corinthians 6:19-20. At the end of the sermon, he led the congregation in a prayer of faith to receive the baptism of the Holy Spirit. Hundreds testified of having prayed the prayer of faith.<\/p>\n<p>The pastors were organized in 10 groups for the baptisms and, according to the district superintendent, &#8220;one could see not just the coordination but also the direction of the Holy Spirit in such a large celebration, fulfilling the words of the apostle Paul &#8211; one body, one Spirit, one God, one faith.&#8221;<\/p>\n<p>This event is the result of a series of holiness services and small groups that have been taking place across the district for the past two years. &#8220;The church is entering a move of the Holy Spirit,&#8221; said the district superintendent. &#8220;Someone may ask, &#8216;What is this?&#8217; It is nothing more than the work of the Holy Spirit because all of us &#8211; pastors, church boards, members &#8211; we are all &#8216;jars of clay&#8217; for God&#8217;s glory and not our own,&#8221; he added.<\/p>\n<p>&#8220;We encourage every church, pastor and member to seek the filling of the Holy Spirit which is the formula God has given to the church in order to fulfil the mandate to go and preach the gospel.<\/p>\n<p>&#8220;Jesus said that there is a party in heaven for one sinner who repents and we believe, on this wonderful day, that party came here to earth among us. Soli Deo Gloria!&#8221; ended superintendent Francisco Cho.<\/p>\n<p>Source: Reverend Francisco Cho Si, Superintendent of the Church of the Nazarene Verapaz North<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-57703 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"69119517_2617929311585424_1949751548489760768_o\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o-1024x683.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69119517_2617929311585424_1949751548489760768_o-1200x800.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"68820062_2617873731590982_3141892349391536128_o\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o-1024x683.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68820062_2617873731590982_3141892349391536128_o-1200x800.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"68951791_2617875388257483_7920148001400553472_o\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o-1024x683.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68951791_2617875388257483_7920148001400553472_o-1200x800.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Bautiso Masivo 1\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1.jpg'><img decoding=\"async\" width=\"200\" height=\"150\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1-200x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1-200x150.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1-300x225.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1-400x300.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1-600x450.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1-768x576.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1-800x600.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1-1024x768.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1-1200x900.jpg 1200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-1.jpg 1280w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Bautiso Masivo 5\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5.jpg'><img decoding=\"async\" width=\"200\" height=\"78\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5-200x78.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5-200x78.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5-300x117.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5-400x156.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5-600x233.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5-768x299.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5-800x311.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5-1024x398.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5-1200x467.jpg 1200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-5.jpg 1280w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"bautizos masivos\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos.jpg'><img decoding=\"async\" width=\"200\" height=\"150\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos-200x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos-200x150.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos-300x225.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos-400x300.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos-600x450.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos-768x576.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos-800x600.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos-1024x768.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos-1200x900.jpg 1200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/bautizos-masivos.jpg 1280w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Bautiso Masivo 3\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1-1024x682.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1-1200x800.jpg 1200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-3-1.jpg 1280w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"68688935_2617873631590992_5030520298441539584_o\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o-1024x683.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68688935_2617873631590992_5030520298441539584_o-1200x800.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"69218230_2617873978257624_5767011583733530624_o\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o-1024x683.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69218230_2617873978257624_5767011583733530624_o-1200x800.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"68990897_2617874141590941_3204602153268150272_o\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o-1024x683.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68990897_2617874141590941_3204602153268150272_o-1200x800.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"68873757_2617873841590971_7866360820282687488_o\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o-1024x683.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/68873757_2617873841590971_7866360820282687488_o-1200x800.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Bautiso Masivo 2\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2-1024x682.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2-1200x800.jpg 1200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-2.jpg 1280w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"69086437_2617903698254652_451893334781198336_o\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o-1024x683.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/69086437_2617903698254652_451893334781198336_o-1200x800.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Bautiso Masivo 6\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6-1024x682.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6-1200x800.jpg 1200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-6.jpg 1280w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Bautiso Masivo 4\" data-caption=\"\" href='https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4.jpg'><img decoding=\"async\" width=\"200\" height=\"133\" src=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4-200x133.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Bautizo Masivo\" srcset=\"https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4-200x133.jpg 200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4-300x200.jpg 300w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4-400x267.jpg 400w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4-600x400.jpg 600w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4-768x512.jpg 768w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4-800x533.jpg 800w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4-1024x682.jpg 1024w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4-1200x800.jpg 1200w, https:\/\/www.mesonaz.org\/wp-content\/uploads\/2019\/08\/Bautiso-Masivo-4.jpg 1280w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>On Sunday August 18th, approximately 8,500 people attended a mass baptism celebration held for the first time by the Church of the Nazarene Verapaz North District in Guatemala. The District&#8217;s 105 churches came together to celebrate the baptism of 697 persons. Starting out from their different locations in the early hours of the morning, the <a href=\"https:\/\/www.mesonaz.org\/en\/more-than-600-people-baptized-in-guatemala-district\/\"> <\/a><\/p>\n","protected":false},"author":5,"featured_media":57523,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[260,1575],"tags":[],"class_list":["post-57703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-norcentral-fields"],"_links":{"self":[{"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/posts\/57703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/comments?post=57703"}],"version-history":[{"count":0,"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/posts\/57703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/media\/57523"}],"wp:attachment":[{"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/media?parent=57703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/categories?post=57703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mesonaz.org\/en\/wp-json\/wp\/v2\/tags?post=57703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}